{"id":2039,"count":1,"description":"","link":"https:\/\/benerbareng.id\/index.php\/tag\/tren-lifestyle\/","name":"tren lifestyle","slug":"tren-lifestyle","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/benerbareng.id\/index.php\/wp-json\/wp\/v2\/tags\/2039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/benerbareng.id\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/benerbareng.id\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/benerbareng.id\/index.php\/wp-json\/wp\/v2\/posts?tags=2039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}