{"id":2067,"count":1,"description":"","link":"https:\/\/benerbareng.id\/index.php\/tag\/budaya-lokal-indonesia\/","name":"budaya lokal indonesia","slug":"budaya-lokal-indonesia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/benerbareng.id\/index.php\/wp-json\/wp\/v2\/tags\/2067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/benerbareng.id\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/benerbareng.id\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/benerbareng.id\/index.php\/wp-json\/wp\/v2\/posts?tags=2067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}